{"id":152,"date":"2023-05-18T17:39:43","date_gmt":"2023-05-18T17:39:43","guid":{"rendered":"https:\/\/1xbets.plus\/congo\/?page_id=152"},"modified":"2026-05-13T10:28:38","modified_gmt":"2026-05-13T10:28:38","slug":"bonus","status":"publish","type":"page","link":"https:\/\/1xbets.plus\/congo\/bonus\/","title":{"rendered":"Bonus"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-152","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bonus et promotions 1xBet Congo 2026<\/title>\n<meta name=\"description\" content=\"Vous trouverez ici une large gamme d&#039;offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu&#039;\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonus et promotions 1xBet Congo 2026\" \/>\n<meta property=\"og:description\" content=\"Vous trouverez ici une large gamme d&#039;offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu&#039;\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1xbets.plus\/congo\/bonus\/\" \/>\n<meta property=\"og:site_name\" content=\"1xbet Boost cd\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:28:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/1xbets.plus\/congo\/bonus\/\",\"url\":\"https:\/\/1xbets.plus\/congo\/bonus\/\",\"name\":\"Bonus et promotions 1xBet Congo 2026\",\"isPartOf\":{\"@id\":\"https:\/\/1xbets.plus\/congo\/#website\"},\"datePublished\":\"2023-05-18T17:39:43+00:00\",\"dateModified\":\"2026-05-13T10:28:38+00:00\",\"description\":\"Vous trouverez ici une large gamme d'offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu'\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits\",\"inLanguage\":\"fr-CD\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/1xbets.plus\/congo\/bonus\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/1xbets.plus\/congo\/#website\",\"url\":\"https:\/\/1xbets.plus\/congo\/\",\"name\":\"1xbet Boost cd\",\"description\":\"My WordPress Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/1xbets.plus\/congo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CD\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonus et promotions 1xBet Congo 2026","description":"Vous trouverez ici une large gamme d'offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu'\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Bonus et promotions 1xBet Congo 2026","og_description":"Vous trouverez ici une large gamme d'offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu'\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits","og_url":"https:\/\/1xbets.plus\/congo\/bonus\/","og_site_name":"1xbet Boost cd","article_modified_time":"2026-05-13T10:28:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/1xbets.plus\/congo\/bonus\/","url":"https:\/\/1xbets.plus\/congo\/bonus\/","name":"Bonus et promotions 1xBet Congo 2026","isPartOf":{"@id":"https:\/\/1xbets.plus\/congo\/#website"},"datePublished":"2023-05-18T17:39:43+00:00","dateModified":"2026-05-13T10:28:38+00:00","description":"Vous trouverez ici une large gamme d'offres de bonus \u26a1\ufe0f Bonus de 100 % sur votre premier d\u00e9p\u00f4t jusqu'\u00e0 250.000 CDF \u2713 Codes promotionnels 1xBet \u2713 Cashback et paris gratuits","inLanguage":"fr-CD","potentialAction":[{"@type":"ReadAction","target":["https:\/\/1xbets.plus\/congo\/bonus\/"]}]},{"@type":"WebSite","@id":"https:\/\/1xbets.plus\/congo\/#website","url":"https:\/\/1xbets.plus\/congo\/","name":"1xbet Boost cd","description":"My WordPress Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1xbets.plus\/congo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CD"}]}},"_links":{"self":[{"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/pages\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":64,"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/pages\/152\/revisions"}],"predecessor-version":[{"id":922,"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/pages\/152\/revisions\/922"}],"wp:attachment":[{"href":"https:\/\/1xbets.plus\/congo\/wp-json\/wp\/v2\/media?parent=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}